{"id":10722,"date":"2021-09-18T11:02:19","date_gmt":"2021-09-18T09:02:19","guid":{"rendered":"https:\/\/spielepost.de\/?p=10722"},"modified":"2021-09-13T11:12:28","modified_gmt":"2021-09-13T09:12:28","slug":"mammoth-mod-minecraft-zum-mmo-tausende-spieler-in-einer-welt","status":"publish","type":"post","link":"https:\/\/spielepost.de\/es\/mammoth-mod-minecraft-a-mmo-miles-de-jugadores-en-un-mundo\/","title":{"rendered":"Mammoth Mod: de Minecraft a MMO: miles de jugadores en un solo mundo"},"content":{"rendered":"<h2><strong>Mammoth Mod: de Minecraft a MMO: miles de jugadores en un solo mundo<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Es lunes en PC Gamer y a\u00fan no hemos tenido un chat de servidor caliente: \u00a1pero no te preocupes! Un pr\u00f3ximo mod de Minecraft con serias ambiciones est\u00e1 a punto de cambiar todo eso, e incluso podr\u00eda tener un mayor impacto en el futuro de la plataforma. En esencia, se trata de un problema: Minecraft procesa toda la informaci\u00f3n de un servidor en una sola CPU (con un solo hilo). As\u00ed que puedes tener el PC m\u00e1s grande y potente del mundo, pero en cuanto tiene que lidiar con varias docenas o incluso cientos de jugadores, el rendimiento se ve gravemente afectado, el tick rate del servidor cae hasta el punto de que se vuelve injugable y ya nadie se divierte.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>El \"r\u00e9cord mundial\" de jugadores simult\u00e1neos de Minecraft<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>El \"r\u00e9cord mundial\" de jugadores simult\u00e1neos de Minecraft en un solo mundo es de 2622, un logro ca\u00f3tico en el que ninguno de esos jugadores pod\u00eda realmente hacer nada, pero oye, estaban ah\u00ed. Eso no fue suficiente para el programador Jackson Roberts. Quer\u00eda un proyecto para completar a principios de 2020 y decidi\u00f3 crear un servidor gigante de Minecraft que pudiera albergar a miles de jugadores sin demora. El software de servidor de un solo hilo existente en Minecraft no estaba claramente a la altura, as\u00ed que Roberts y su colaborador Harvey298 decidieron crear su propio servidor, al que llamaron Mammoth.<\/p>\n<p>El primer intento, como explica Roberts, fue un sistema de prueba de concepto que divid\u00eda un mundo de Minecraft en 1024 bloques, cada uno gestionado por su propio servidor: Las zonas fronterizas estaban sincronizadas y los servidores transfer\u00edan los objetos en movimiento entre s\u00ed. Sin embargo, hab\u00eda demasiados problemas: los jugadores no pod\u00edan verse entre s\u00ed \"a trav\u00e9s de los servidores\", el fallo de un servidor hac\u00eda que esa parte del mundo fuera inaccesible y, b\u00e1sicamente, la soluci\u00f3n no hac\u00eda nada cuando muchos jugadores se reun\u00edan en una zona peque\u00f1a.<\/p>\n<p>Tras esta experiencia, Roberts se fij\u00f3 una serie de objetivos para Mammoth, entre ellos Los jugadores deben poder verse unos a otros aunque est\u00e9n en diferentes servidores; si un jugador coloca un bloque o actualiza un escudo, esto debe ser inmediatamente visible para todos los dem\u00e1s jugadores; si un servidor se cae, todo el mundo debe seguir siendo accesible; si es necesario, se pueden a\u00f1adir o quitar servidores a voluntad para adaptarse al n\u00famero de jugadores.<\/p>\n<p>La idea que ten\u00eda era una base de datos backend centralizada que pudiera comunicarse entre los servidores de Minecraft a medida que aparecieran y desaparecieran, y transmitir continuamente mensajes sobre, por ejemplo, los movimientos de los jugadores. Despu\u00e9s de probar algunos programas existentes, como redis y SpatialOS, Roberts descubri\u00f3 que no eran adecuados para sus prop\u00f3sitos y decidi\u00f3 desarrollar su propio programa, WorldQL, que describe como \"una base de datos espacial en tiempo real con capacidad de scripting para juegos multijugador [que] puede sustituir a los servidores de juegos tradicionales o utilizarse para equilibrar la carga de los servidores existentes\".<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>La nueva versi\u00f3n de Mammoth<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>La nueva versi\u00f3n de Mammoth, que saldr\u00e1 a la venta el 8 de septiembre, se basa en WorldQL, que \"almacena todos los cambios permanentes del mundo y pasa la informaci\u00f3n de los jugadores en tiempo real (por ejemplo, la ubicaci\u00f3n) entre los servidores\". B\u00e1sicamente, cada servidor informa constantemente de sus datos a World QL, que a su vez hace preguntas a otros servidores bas\u00e1ndose en estos informes: Si sabe que un jugador est\u00e1 cerca de otro, y el servidor del primero dice que se ha movido, WorldQL pregunta qu\u00e9 est\u00e1 haciendo el otro.<\/p>\n<p>\"En Mammoth, ning\u00fan servidor de Minecraft es responsable de almacenar el mundo. Todos los cambios en los bloques se almacenan de forma centralizada en WorldQL. Estos cambios est\u00e1n indexados por coordenadas de chunk y tiempo, por lo que un servidor de Minecraft s\u00f3lo puede solicitar las actualizaciones que necesita desde la \u00faltima vez que se sincroniz\u00f3 un chunk.\"<\/p>\n<p>El post de Jackson se adentra en aspectos apasionantes como la \"sincronizaci\u00f3n de bloques en tiempo real\", los corredores de mensajes y el futuro potencial de los minijuegos de Minecraft para ser creados en el entorno de scripting de WorldQL (porque podr\u00e1n explotar el escalado de jugadores por defecto). Aqu\u00ed est\u00e1 la p\u00e1gina de Github de Mammoth.<\/p>\n<p>El debut de Mammoth ser\u00e1 de especial inter\u00e9s para algunas de las comunidades de Minecraft m\u00e1s inusuales, como las que disfrutan jugando en servidores de anarqu\u00eda, y permitir\u00e1 toda una serie de otras actividades a gran escala que antes no eran posibles. Es de esperar que esto se pruebe en servidores como el 2b2t y, si funciona como se dice sin caerse, se convierta r\u00e1pidamente en parte del escenario. Como puedes ver en nuestra lista de los mejores servidores de Minecraft, a la gente siempre se le ocurren formas locas y maravillosas de jugar, y si Mammoth est\u00e1 a la altura de su promesa, podr\u00eda hacer honor a su nombre.<\/p>\n<p>&nbsp;<\/p>\n<p>Por cierto, puedes encontrar un buen sitio web con ideas de construcci\u00f3n para Minecraft aqu\u00ed <a href=\"https:\/\/minecraft-bauideen.de\/\" target=\"_blank\" rel=\"noopener\">https:\/\/minecraft-bauideen.de\/<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Mammoth Mod: de Minecraft a MMO: miles de jugadores en un solo mundo Es lunes en PC Gamer y a\u00fan no hemos tenido una charla caliente sobre servidores: \u00a1pero no te preocupes! Un pr\u00f3ximo mod de Minecraft con serias ambiciones est\u00e1 a punto de cambiar todo eso, e incluso podr\u00eda tener un mayor impacto en el futuro de la plataforma. Esencialmente [...]<\/p>","protected":false},"author":1,"featured_media":10723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1,265,339,98,34,46,292,45],"tags":[4456,4458,4457],"class_list":["post-10722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-browser-games","category-minecraft","category-mmos","category-news","category-spiele-video","category-spiele-news","category-video","tag-mammoth-mod","tag-minecraft-mod","tag-minecraft-zum-mmo"],"_links":{"self":[{"href":"https:\/\/spielepost.de\/es\/wp-json\/wp\/v2\/posts\/10722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spielepost.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spielepost.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spielepost.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spielepost.de\/es\/wp-json\/wp\/v2\/comments?post=10722"}],"version-history":[{"count":2,"href":"https:\/\/spielepost.de\/es\/wp-json\/wp\/v2\/posts\/10722\/revisions"}],"predecessor-version":[{"id":10725,"href":"https:\/\/spielepost.de\/es\/wp-json\/wp\/v2\/posts\/10722\/revisions\/10725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spielepost.de\/es\/wp-json\/wp\/v2\/media\/10723"}],"wp:attachment":[{"href":"https:\/\/spielepost.de\/es\/wp-json\/wp\/v2\/media?parent=10722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spielepost.de\/es\/wp-json\/wp\/v2\/categories?post=10722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spielepost.de\/es\/wp-json\/wp\/v2\/tags?post=10722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}